{"id":104,"date":"2017-06-26T21:40:04","date_gmt":"2017-06-26T19:40:04","guid":{"rendered":"http:\/\/dev.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg"},"modified":"2017-06-26T21:40:04","modified_gmt":"2017-06-26T19:40:04","slug":"2016-06-07_elmolo_img_2493","status":"inherit","type":"attachment","link":"http:\/\/www.ujuzi.media\/en\/2016-06-07_elmolo_img_2493\/","title":{"rendered":"2016-06-07_elmolo_IMG_2493"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"spay_email":""},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a91V9t-1G","jetpack_likes_enabled":false,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg'><img width=\"300\" height=\"200\" src=\"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=300%2C200\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?w=1024 1024w, https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?resize=300%2C200 300w, https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?resize=768%2C512 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"104\" data-permalink=\"http:\/\/www.ujuzi.media\/en\/2016-06-07_elmolo_img_2493\/\" data-orig-file=\"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=1024%2C683\" data-orig-size=\"1024,683\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"2016-06-07_elmolo_IMG_2493\" data-image-description=\"\" data-medium-file=\"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=300%2C200\" data-large-file=\"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=640%2C427\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":683,"file":"2017\/06\/2016-06-07_elmolo_IMG_2493.jpg","sizes":{"thumbnail":{"file":"2016-06-07_elmolo_IMG_2493-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?resize=150%2C150"},"medium":{"file":"2016-06-07_elmolo_IMG_2493-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=300%2C200"},"medium_large":{"file":"2016-06-07_elmolo_IMG_2493-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=640%2C427"},"large":{"file":"2016-06-07_elmolo_IMG_2493-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=640%2C427"},"twentyseventeen-thumbnail-avatar":{"file":"2016-06-07_elmolo_IMG_2493-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"http:\/\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493-100x100.jpg"},"full":{"file":"2016-06-07_elmolo_IMG_2493.jpg?fit=1024%2C683","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/i2.wp.com\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg?fit=1024%2C683"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"http:\/\/www.ujuzi.media\/wp-content\/uploads\/2017\/06\/2016-06-07_elmolo_IMG_2493.jpg","_links":{"self":[{"href":"http:\/\/www.ujuzi.media\/en\/wp-json\/wp\/v2\/media\/104"}],"collection":[{"href":"http:\/\/www.ujuzi.media\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.ujuzi.media\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.ujuzi.media\/en\/wp-json\/wp\/v2\/users\/1"}]}}